{"id":2,"name":"Elvira Gizatullina","url":"https:\/\/water4lifeministry.org\/","description":"","link":"https:\/\/water4lifeglobal.org\/fr\/author\/elvira\/","slug":"elvira","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g"},"meta":{"jetpack_donation_warning_dismissed":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elvira Gizatullina, Author at Water4Life Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/water4lifeglobal.org\/fr\/auteur\/elvira\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Elvira Gizatullina, Author at Water4Life Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/water4lifeglobal.org\/fr\/auteur\/elvira\/\" \/>\n<meta property=\"og:site_name\" content=\"Water4Life Global\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/\",\"url\":\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/\",\"name\":\"Elvira Gizatullina, Author at Water4Life Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/water4lifeglobal.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Elvira Gizatullina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/#website\",\"url\":\"https:\\\/\\\/water4lifeglobal.org\\\/\",\"name\":\"Water4Life Global\",\"description\":\"All donations will help bring clean water to communities in need\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/water4lifeglobal.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/#\\\/schema\\\/person\\\/c21500ef2538f70303255dafb6e2208b\",\"name\":\"Elvira Gizatullina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g\",\"caption\":\"Elvira Gizatullina\"},\"sameAs\":[\"https:\\\/\\\/water4lifeministry.org\\\/\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/water4lifeglobal.org\\\/author\\\/elvira\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elvira Gizatullina, Author at Water4Life Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/water4lifeglobal.org\/fr\/auteur\/elvira\/","og_locale":"fr_FR","og_type":"profile","og_title":"Elvira Gizatullina, Author at Water4Life Global","og_url":"https:\/\/water4lifeglobal.org\/fr\/auteur\/elvira\/","og_site_name":"Water4Life Global","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/water4lifeglobal.org\/author\/elvira\/","url":"https:\/\/water4lifeglobal.org\/author\/elvira\/","name":"Elvira Gizatullina, Author at Water4Life Global","isPartOf":{"@id":"https:\/\/water4lifeglobal.org\/#website"},"breadcrumb":{"@id":"https:\/\/water4lifeglobal.org\/author\/elvira\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/water4lifeglobal.org\/author\/elvira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/water4lifeglobal.org\/author\/elvira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/water4lifeglobal.org\/"},{"@type":"ListItem","position":2,"name":"Archives for Elvira Gizatullina"}]},{"@type":"WebSite","@id":"https:\/\/water4lifeglobal.org\/#website","url":"https:\/\/water4lifeglobal.org\/","name":"Water4Life Global","description":"All donations will help bring clean water to communities in need","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/water4lifeglobal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/water4lifeglobal.org\/#\/schema\/person\/c21500ef2538f70303255dafb6e2208b","name":"Elvira Gizatullina","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0327802791034040d4a858806fe834f8edc5fda116b5dbbe2d8aabdb3c68dcb4?s=96&d=mm&r=g","caption":"Elvira Gizatullina"},"sameAs":["https:\/\/water4lifeministry.org\/"],"mainEntityOfPage":{"@id":"https:\/\/water4lifeglobal.org\/author\/elvira\/"}}]}},"_links":{"self":[{"href":"https:\/\/water4lifeglobal.org\/fr\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/water4lifeglobal.org\/fr\/wp-json\/wp\/v2\/users"}]}}